{"id":8223,"date":"2024-03-01T10:12:40","date_gmt":"2024-03-01T10:12:40","guid":{"rendered":"http:\/\/europackwine.fr\/?post_type=product&#038;p=8223"},"modified":"2026-03-31T09:26:45","modified_gmt":"2026-03-31T09:26:45","slug":"carton-26-x-24-x-37-cm","status":"publish","type":"product","link":"https:\/\/europackwine.fr\/it\/prodotto\/carton-26-x-24-x-37-cm\/","title":{"rendered":"CAPA 04 - Cartone 26 x 24 x 37 cm"},"content":{"rendered":"<p data-sourcepos=\"1:1-1:91\"><strong>CAPA 04 - Cartone 26 x 24 x 37 cm<br \/>\n<\/strong>Le <strong>CAPA 04<\/strong> \u00e8 un cartone di sovraimballaggio a singola onda progettato per contenere e proteggere 4 scatole (EUPA 01) in polistirene durante il trasporto. Perfettamente adatto per la spedizione di una bottiglia, ed offrirvi cos\u00ec una protezione ottimale alle vostre bottiglie. Robusto ed elegante, \u00e8 ideale per il trasporto e lo stoccaggio dei vostri preziosi crus.<\/p>\n<p data-sourcepos=\"17:1-17:28\"><strong>Pratico ed economico:<\/strong><\/p>\n<p data-sourcepos=\"17:1-17:28\">Il nostro prodotto viene consegnato in scatole da 25 cartoni per facilitarne lo stoccaggio e la movimentazione. Si impilano facilmente per risparmiare peso e pesano solo 238 g per ridurre i costi di spedizione.<\/p>\n<p data-sourcepos=\"25:1-25:23\"><strong>Soluzione completa :<\/strong><\/p>\n<p>Se non conoscete la nostra soluzione di imballaggio, vi consigliamo di ordinare direttamente la soluzione completa EURO 04 (<a href=\"http:\/\/europackwine.fr\/it\/prodotto\/emballage-vin-4-bouteilles\/\"><strong>visualizza il prodotto<\/strong><\/a>) che contiene tutti gli elementi :<\/p>\n<ul>\n<li>1 collo CAPA04<\/li>\n<li>4 scatole di polistirolo riferimento EUPA 01 : <a href=\"http:\/\/europackwine.fr\/it\/prodotto\/coffret-polystyrene-1-bouteille\/\"><strong>visualizza il prodotto<\/strong><\/a><\/li>\n<\/ul>\n<p data-sourcepos=\"40:1-40:15\"><strong>Vantaggi :<\/strong><\/p>\n<ul data-sourcepos=\"42:1-47:0\">\n<li data-sourcepos=\"42:1-42:22\">Robusto e resistente<\/li>\n<li data-sourcepos=\"43:1-43:57\">Perfettamente adatto alle scatole universali in polistirolo<\/li>\n<li data-sourcepos=\"44:1-44:24\">Pratico ed economico<\/li>\n<li data-sourcepos=\"45:1-45:20\">Leggero e impilabile<\/li>\n<li data-sourcepos=\"46:1-47:0\">Qualit\u00e0 superiore<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p data-sourcepos=\"1:1-1:91\"><strong>CAPA 04 - Cartone 26 x 24 x 37 cm, <\/strong>la soluzione ideale per i professionisti del vino che cercano un imballaggio di alta qualit\u00e0 per le loro bottiglie.<strong><br \/>\n<\/strong>Confezione : Scatola da 25 scatole<\/p>\n<hr \/>\n<table class=\"size-table price-table table-technical-information\" style=\"height: 46px; width: 500px;\" data-v-33004ae6=\"\">\n<thead id=\"table-head-product-batch\" data-v-33004ae6=\"\">\n<tr style=\"height: 23px;\" data-v-33004ae6=\"\">\n<th class=\"column-pack table-price-right pt-1 pb-2\" style=\"text-align: center; height: 23px; width: 70.8125px;\" data-v-33004ae6=\"\"><span data-v-33004ae6=\"\">25 cartoni<\/span><\/th>\n<th class=\"column-box pt-1 pb-2\" style=\"text-align: center; height: 23px; width: 78.5938px;\" data-v-33004ae6=\"\">125 sca<\/th>\n<th class=\"column-size pt-1 pb-2\" style=\"text-align: center; height: 23px; width: 74.7031px;\" data-v-33004ae6=\"\"><span data-v-33004ae6=\"\">225 cartoni<\/span><\/th>\n<th class=\"column-size-box pt-1 pb-2\" style=\"text-align: center; height: 23px; width: 78.5938px;\" data-v-33004ae6=\"\">425 scatoloni<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"table-hover\" data-v-33004ae6=\"\">\n<tr style=\"height: 23px;\" data-v-33004ae6=\"\">\n<td class=\"pl-0 pr-0\" style=\"text-align: center; height: 23px; width: 70.8125px;\" data-v-33004ae6=\"\">1,90\u20ac\/u<\/td>\n<td class=\"pl-0 pr-0\" style=\"text-align: center; height: 23px; width: 78.5938px;\" data-v-33004ae6=\"\">1,83\u20ac\/u<\/td>\n<td class=\"pl-0 pr-0\" style=\"text-align: center; height: 23px; width: 74.7031px;\" data-v-33004ae6=\"\">1,73\u20ac\/u<\/td>\n<td class=\"pl-0 pr-0\" style=\"text-align: center; height: 23px; width: 78.5938px;\" data-v-33004ae6=\"\">1,65\u20ac\/u<\/td>\n<\/tr>\n<\/tbody>\n<\/table>","protected":false},"featured_media":1809,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[296],"product_tag":[],"class_list":{"0":"post-8223","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-cartons","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/europackwine.fr\/it\/wp-json\/wp\/v2\/product\/8223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/europackwine.fr\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/europackwine.fr\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/europackwine.fr\/it\/wp-json\/wp\/v2\/comments?post=8223"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/europackwine.fr\/it\/wp-json\/wp\/v2\/media\/1809"}],"wp:attachment":[{"href":"https:\/\/europackwine.fr\/it\/wp-json\/wp\/v2\/media?parent=8223"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/europackwine.fr\/it\/wp-json\/wp\/v2\/product_brand?post=8223"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/europackwine.fr\/it\/wp-json\/wp\/v2\/product_cat?post=8223"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/europackwine.fr\/it\/wp-json\/wp\/v2\/product_tag?post=8223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}