{"id":177,"count":1,"description":"","link":"https:\/\/europackwine.fr\/es\/tag\/fraicheur\/","name":"fraicheur","slug":"fraicheur","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/europackwine.fr\/es\/wp-json\/wp\/v2\/tags\/177","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/europackwine.fr\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/europackwine.fr\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/europackwine.fr\/es\/wp-json\/wp\/v2\/posts?tags=177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}