{"id":1091,"date":"2021-04-19T07:49:39","date_gmt":"2021-04-19T07:49:39","guid":{"rendered":"https:\/\/europackwine.staging-lab.co\/?post_type=product&#038;p=1091"},"modified":"2026-03-30T08:43:24","modified_gmt":"2026-03-30T08:43:24","slug":"coffret-polystyrene-1-bouteille","status":"publish","type":"product","link":"https:\/\/europackwine.fr\/es\/producto\/coffret-polystyrene-1-bouteille\/","title":{"rendered":"EUPA 01 - Caja de poliestireno 1 botella"},"content":{"rendered":"<p data-sourcepos=\"1:1-1:80\"><strong>EUPA 01 : Caja de poliestireno 1 botella<\/strong><\/p>\n<p data-sourcepos=\"1:1-1:80\"><strong>Proteja sus botellas de vino con total seguridad gracias a nuestra funda protectora universal.<\/strong><\/p>\n<p>Esta caja de poliestireno expandido (EPS) est\u00e1 dise\u00f1ada para ofrecer una protecci\u00f3n \u00f3ptima y universal a sus botellas de vino durante el transporte.<\/p>\n<p data-sourcepos=\"17:1-17:28\"><strong>Pr\u00e1ctico y econ\u00f3mico:<\/strong><\/p>\n<p data-sourcepos=\"17:1-17:28\">Nuestro producto se entrega en cajas de 50 unidades para facilitar su almacenamiento y manipulaci\u00f3n. Se apilan f\u00e1cilmente para ahorrar peso y pesan solo 80 g para reducir los gastos de env\u00edo.<\/p>\n<p data-sourcepos=\"20:1-20:15\"><strong>Informaci\u00f3n importante:<\/strong><\/p>\n<p data-sourcepos=\"22:1-22:143\">La caja de poliestireno de 1 botella funciona como acolchado y requiere una sobrecaja para mantenerla en su sitio y garantizar su integridad durante el env\u00edo.<\/p>\n<p data-sourcepos=\"22:1-22:143\"><strong>Ventajas :\u00a0<\/strong><\/p>\n<ul data-sourcepos=\"5:1-8:0\">\n<li data-sourcepos=\"5:1-6:52\">Protecci\u00f3n: el poliestireno es un material protector hecho de espuma de poliestireno expandido (EPS) que protege el vino de golpes y vibraciones durante el transporte y la manipulaci\u00f3n.<\/li>\n<li data-sourcepos=\"5:1-5:272\">Aislamiento<strong>\u00a0:<\/strong> El EPS tambi\u00e9n es un buen aislante, que mantiene las botellas de vino a una temperatura constante durante el transporte y el almacenamiento.<\/li>\n<li data-sourcepos=\"16:1-16:106\">Ligereza: el poliestireno es un material ligero, lo que facilita el transporte y la manipulaci\u00f3n de las cajas de vino. Tambi\u00e9n es bueno para el medio ambiente, ya que reduce las emisiones de carbono.<\/li>\n<li data-sourcepos=\"16:1-16:106\">Reciclable: las cajas de poliestireno son reciclables y pueden convertirse en nuevos productos, como cojines, envases para alimentos, etc.<\/li>\n<\/ul>\n<p data-sourcepos=\"25:1-25:23\"><strong>Soluci\u00f3n completa :<\/strong><\/p>\n<p>Si no est\u00e1 familiarizado con nuestra soluci\u00f3n de envasado, le recomendamos que pida directamente un <strong>soluci\u00f3n completa<\/strong> en funci\u00f3n del n\u00famero de botellas que desee enviar:<\/p>\n<ul>\n<li>Para 1 botella :\n<ul>\n<li>EURO 01 : <strong><a href=\"http:\/\/europackwine.fr\/es\/producto\/emballage-vin-1-bouteille\/\">ver el producto<\/a><\/strong><\/li>\n<\/ul>\n<\/li>\n<li>Para 2 botellas :\n<ul>\n<li>EURO 02 : <strong><a href=\"http:\/\/europackwine.fr\/es\/producto\/emballage-vin-2-bouteilles\/\">ver el producto<\/a><\/strong><\/li>\n<\/ul>\n<\/li>\n<li>Para 4 botellas :\n<ul>\n<li>EURO 04 :\u00a0<strong><a href=\"http:\/\/europackwine.fr\/es\/producto\/emballage-vin-4-bouteilles\/\">ver el producto<\/a><\/strong><\/li>\n<\/ul>\n<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p data-sourcepos=\"1:1-1:91\"><strong>EUPA 01 - Estuche de poliestireno, 1 botella, <\/strong>la soluci\u00f3n ideal para los profesionales del vino que buscan un empaque de calidad superior para su botella.<br \/>\nEmbalaje : Caja de 50<\/p>\n<hr \/>\n<table class=\"size-table price-table table-technical-information\" style=\"width: 500px;\" data-v-33004ae6=\"\">\n<thead id=\"table-head-product-batch\" data-v-33004ae6=\"\">\n<tr data-v-33004ae6=\"\">\n<th class=\"column-pack table-price-right pt-1 pb-2\" data-v-33004ae6=\"\"><span data-v-33004ae6=\"\">50 cajas<\/span><\/th>\n<th class=\"column-box pt-1 pb-2\" data-v-33004ae6=\"\">150 cajas<\/th>\n<th class=\"column-size pt-1 pb-2\" data-v-33004ae6=\"\"><span data-v-33004ae6=\"\">250 cajas<\/span><\/th>\n<th class=\"column-size-box pt-1 pb-2\" data-v-33004ae6=\"\">450 cajas<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"table-hover\" data-v-33004ae6=\"\">\n<tr data-v-33004ae6=\"\">\n<td class=\"pl-0 pr-0\" data-v-33004ae6=\"\">1,46\u20ac\/u<\/td>\n<td class=\"pl-0 pr-0\" data-v-33004ae6=\"\">1,38\u20ac\/u<\/td>\n<td class=\"pl-0 pr-0\" data-v-33004ae6=\"\">1,26\u20ac\/u<\/td>\n<td class=\"pl-0 pr-0\" data-v-33004ae6=\"\">1,18\u20ac\/u<\/td>\n<\/tr>\n<\/tbody>\n<\/table>","protected":false},"featured_media":1814,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[295],"product_tag":[],"class_list":{"0":"post-1091","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-coffrets","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/europackwine.fr\/es\/wp-json\/wp\/v2\/product\/1091","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/europackwine.fr\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/europackwine.fr\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/europackwine.fr\/es\/wp-json\/wp\/v2\/comments?post=1091"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/europackwine.fr\/es\/wp-json\/wp\/v2\/media\/1814"}],"wp:attachment":[{"href":"https:\/\/europackwine.fr\/es\/wp-json\/wp\/v2\/media?parent=1091"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/europackwine.fr\/es\/wp-json\/wp\/v2\/product_brand?post=1091"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/europackwine.fr\/es\/wp-json\/wp\/v2\/product_cat?post=1091"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/europackwine.fr\/es\/wp-json\/wp\/v2\/product_tag?post=1091"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}